{"id":14,"count":0,"description":"Discounts on furniture, home decor, and household items. Stores related to home improvement, decor, and gardening. Lifestyle stores. Smart home products.","link":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/","name":"Home &amp; Garden","slug":"home-garden","taxonomy":"categories","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home &amp; Garden Archives - Coupon Code 2026 WW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home &amp; Garden Archives - Coupon Code 2026 WW\" \/>\n<meta property=\"og:description\" content=\"Discounts on furniture, home decor, and household items. Stores related to home improvement, decor, and gardening. Lifestyle stores. Smart home products.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/\" \/>\n<meta property=\"og:site_name\" content=\"Coupon Code 2026 WW\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/categories\\\/home-garden\\\/\",\"url\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/categories\\\/home-garden\\\/\",\"name\":\"Home &amp; Garden Archives - Coupon Code 2026 WW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/categories\\\/home-garden\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/categories\\\/home-garden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home &amp; Garden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/#website\",\"url\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/\",\"name\":\"Coupon Code 2026 WW\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/couponcode2026.com\\\/ww\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home &amp; Garden Archives - Coupon Code 2026 WW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/","og_locale":"en_US","og_type":"article","og_title":"Home &amp; Garden Archives - Coupon Code 2026 WW","og_description":"Discounts on furniture, home decor, and household items. Stores related to home improvement, decor, and gardening. Lifestyle stores. Smart home products.","og_url":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/","og_site_name":"Coupon Code 2026 WW","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/","url":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/","name":"Home &amp; Garden Archives - Coupon Code 2026 WW","isPartOf":{"@id":"https:\/\/couponcode2026.com\/ww\/#website"},"breadcrumb":{"@id":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/couponcode2026.com\/ww\/categories\/home-garden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/couponcode2026.com\/ww\/"},{"@type":"ListItem","position":2,"name":"Home &amp; Garden"}]},{"@type":"WebSite","@id":"https:\/\/couponcode2026.com\/ww\/#website","url":"https:\/\/couponcode2026.com\/ww\/","name":"Coupon Code 2026 WW","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/couponcode2026.com\/ww\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/couponcode2026.com\/ww\/wp-json\/wp\/v2\/coupon-categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponcode2026.com\/ww\/wp-json\/wp\/v2\/coupon-categories"}],"about":[{"href":"https:\/\/couponcode2026.com\/ww\/wp-json\/wp\/v2\/taxonomies\/categories"}],"wp:post_type":[{"href":"https:\/\/couponcode2026.com\/ww\/wp-json\/wp\/v2\/coupon?coupon-categories=14"},{"href":"https:\/\/couponcode2026.com\/ww\/wp-json\/wp\/v2\/blogs?coupon-categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}